{"id":116976,"date":"2019-04-23T13:19:34","date_gmt":"2019-04-23T13:19:34","guid":{"rendered":"https:\/\/food.r-biopharm.com\/news\/avena-senza-glutine-come-garantire-prodotti-sicuri\/"},"modified":"2019-07-17T08:41:49","modified_gmt":"2019-07-17T08:41:49","slug":"avena-senza-glutine-come-garantire-prodotti-sicuri","status":"publish","type":"post","link":"https:\/\/food.r-biopharm.com\/it\/news\/avena-senza-glutine-come-garantire-prodotti-sicuri\/","title":{"rendered":"Avena senza glutine: come garantire prodotti sicuri"},"content":{"rendered":"<strong>Essendo ricca di vitamine, minerali e fibre, l&#8217;avena \u00e8 una valida aggiunta alla dieta, specialmente per quella priva di glutine. Tuttavia, la produzione di prodotti a base di avena senza di glutine presenta alcune insidie.<\/strong><\/p>\n<p><!--more--><\/p>\n<p>Il consumo di avena in Nord America e in Europa \u00e8 in aumento da diversi anni. I prodotti senza glutine di avena, fatti con avena speciale, non contaminata da glutine di frumento, segale o orzo, sono di vitale importanza nella dieta priva di glutine. L&#8217;innesco della celiachia \u00e8 l&#8217;intolleranza alle prolamine da frumento (gliadina), segale (secaline) e orzo (ordaina), mentre la prolamina avenina specifica dell&#8217;avena nella maggior parte dei casi non provoca alcuna reazione. C&#8217;\u00e8 una grande discussione sull&#8217;uso dell&#8217;avena nella dieta priva di glutine, ma nel frattempo, la maggior parte dei paesi concorda sul fatto che l&#8217;avena non contaminata \u00e8 ben tollerata da quasi tutte le persone celiache. Ad esempio, i prodotti provenienti da avena non contaminata possono essere etichettati come &#8220;senza glutine&#8221; nell&#8217;Unione Europea. A tal fine \u00e8 necessario che l&#8217;avena sia prodotta e lavorata separatamente e contenga meno di 20 mg di glutine per kg. L&#8217;avena convenzionale non \u00e8 adatta alle persone celiache perch\u00e8 \u00e8 altamente contaminata da frumento, segale o orzo. Questa contaminazione si verifica ad esempio:<\/p>\n<ul>\n<li>quando l&#8217;avena viene coltivata su campi dove precedentemente venivano coltivati grano, segale o orzo<\/li>\n<li>quando il grano, la segale o l&#8217;orzo crescono nei campi vicini<\/li>\n<li>quando l&#8217;avena viene conservata in silos insieme ad altri cereali<\/li>\n<li>quando l&#8217;avena viene macinata in mulini dove vengono macinati altri cereali<\/li>\n<li>quando le attrezzature utilizzate per la raccolta, il trasporto, la produzione o l&#8217;imballaggio vengono utilizzate anche per altri cereali<\/li>\n<\/ul>\n<p><\/p>\n<h3>Difficolt\u00e0 nella determinazione del glutine nell&#8217;avena<\/h3>\n<p> <a href=\"https:\/\/www.youtube.com\/watch?v=21bT6kKnGHo\">https:\/\/www.youtube.com\/watch?v=21bT6kKnGHo<\/a>Per garantire che un prodotto sia privo di contaminazioni, deve essere analizzato. Per la determinazione del glutine negli alimenti, sono stati stabiliti da molti anni sistemi validati, in particolare l&#8217;ELISA con anticorpo R5, che \u00e8 raccomandato dal Codex Alimentarius e AOAC (<a href=\"https:\/\/food.r-biopharm.com\/products\/ridascreen-gliadin\/\">RIDASCREEN\u00ae Gliadin<\/a>). Tuttavia, durante l&#8217;analisi dell&#8217;avena, i test hanno dei punti deboli. La ragione di questo \u00e8 che il glutine \u00e8 costituito da prolamine e gluteline, mentre l&#8217;anticorpo R5 reagisce in gran parte solo con le prolamine. Il numero di epitopi reattivi per le prolamine \u00e8 pi\u00f9 alto nella segale e nell&#8217;orzo che nel grano, portando ad una sovra-determinazione quando in un campione \u00e8 presente segale o orzo. Nella maggior parte dei casi, questo non \u00e8 un problema in quanto il grano \u00e8 quasi sempre la causa di una contaminazione non intenzionale. Tuttavia, l&#8217;avena \u00e8 spesso contaminata anche con segale o orzo, causando risultati inaccurati. L&#8217;anticorpo G12 alternativo, utilizzato in alcuni altri test, non \u00e8 adatto in quanto mostra una cross-reazioni con l&#8217;avena.<\/p>\n<h3>Un nuovo metodo diagnostico<\/h3>\n<p>Con l&#8217;obiettivo di misurare in modo affidabile la concentrazione di glutine anche nei prodotti a base di avena, l&#8217;AOAC ha definito i requisiti per un nuovo metodo diagnostico (<a href=\"http:\/\/www.aoac.org\/AOAC_Prod_Imis\/AOAC_Docs\/ISPAM\/SMPR_2017.021.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">AOAC SMPR\u00ae 2017.021<\/a>). Il primo sistema che soddisfa questi requisiti \u00e8 ora disponibile: il nuovo RIDASCREEN\u00ae Total Gluten (Art. No. R7041) rileva prolammine insieme alle gluteline e determina quindi il contenuto totale di glutine di frumento, segale e orzo. La sovradeterminazione nel caso di segale e orzo \u00e8 quindi ridotta.<p><a href=\"mailto:info@r-biopharm.de\" title=\"Hai domande sulla determinazione del glutine nell&#8217;avena o desiderate ricevere informazioni sul kit RIDASCREEN\u00ae Total Gluten? Contattaci &#8211; o incontraci ad un &lt;a href=&quot;https:\/\/food.r-biopharm.com\/events\/&quot;&gt;evento&lt;\/a&gt; vicino a te!\" class=\"button button--large\">Contattaci<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Essendo ricca di vitamine, minerali e fibre, l&#8217;avena \u00e8 una valida aggiunta alla dieta, specialmente per quella priva di glutine. Tuttavia, la produzione di prodotti a base di avena senza di glutine presenta alcune insidie.<\/p>\n","protected":false},"author":27,"featured_media":116257,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"442","_seopress_titles_title":"","_seopress_titles_desc":"Essendo ricca di vitamine, minerali e fibre, l'avena \u00e8 una preziosa aggiunta alla dieta priva di glutine. Ma la produzione di prodotti di avena senza glutine ha alcune insidie.","_seopress_robots_index":"","_seopress_analysis_target_kw":"avena","content-type":"","_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","inline_featured_image":false,"footnotes":""},"analyte":[1181,1236],"technology":[],"industry":[713],"newstype":[],"class_list":["post-116976","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","analyte-allergeni-alimentari","analyte-cereali-contenenti-glutine","industry-cereali"],"acf":[],"_links":{"self":[{"href":"https:\/\/food.r-biopharm.com\/it\/wp-json\/wp\/v2\/posts\/116976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/food.r-biopharm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/food.r-biopharm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/food.r-biopharm.com\/it\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/food.r-biopharm.com\/it\/wp-json\/wp\/v2\/comments?post=116976"}],"version-history":[{"count":4,"href":"https:\/\/food.r-biopharm.com\/it\/wp-json\/wp\/v2\/posts\/116976\/revisions"}],"predecessor-version":[{"id":118462,"href":"https:\/\/food.r-biopharm.com\/it\/wp-json\/wp\/v2\/posts\/116976\/revisions\/118462"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/food.r-biopharm.com\/it\/wp-json\/wp\/v2\/media\/116257"}],"wp:attachment":[{"href":"https:\/\/food.r-biopharm.com\/it\/wp-json\/wp\/v2\/media?parent=116976"}],"wp:term":[{"taxonomy":"analyte","embeddable":true,"href":"https:\/\/food.r-biopharm.com\/it\/wp-json\/wp\/v2\/analyte?post=116976"},{"taxonomy":"technology","embeddable":true,"href":"https:\/\/food.r-biopharm.com\/it\/wp-json\/wp\/v2\/technology?post=116976"},{"taxonomy":"industry","embeddable":true,"href":"https:\/\/food.r-biopharm.com\/it\/wp-json\/wp\/v2\/industry?post=116976"},{"taxonomy":"newstype","embeddable":true,"href":"https:\/\/food.r-biopharm.com\/it\/wp-json\/wp\/v2\/newstype?post=116976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}