{"id":119881,"date":"2019-09-23T14:00:28","date_gmt":"2019-09-23T14:00:28","guid":{"rendered":"https:\/\/food.r-biopharm.com\/news\/brettanomyces-nel-vino-come-rilevare-il-deterioramento-del-lievito\/"},"modified":"2019-09-23T14:08:48","modified_gmt":"2019-09-23T14:08:48","slug":"brettanomyces-nel-vino-come-rilevare-il-deterioramento-del-lievito","status":"publish","type":"post","link":"https:\/\/food.r-biopharm.com\/it\/news\/brettanomyces-nel-vino-come-rilevare-il-deterioramento-del-lievito\/","title":{"rendered":"Brettanomyces nel vino: come rilevare il deterioramento del lievito"},"content":{"rendered":"<p><strong>I lieviti <em>Brettanomyces<\/em> provocano il cosiddetto &#8220;Brett&#8221; off-flavour: un odore sgradevole di cavallo, cuoio, sudore o persino urina. La rilevazione precoce di una possibile contaminazione \u00e8 di grande importanza per i viticoltori.<\/strong><!--more--><\/p>\n<p><em>Dekkera bruxellensis<\/em> (noto anche come <em>Brettanomyces bruxellensis<\/em> o &#8220;Brett&#8221; in breve) \u00e8 considerato il pi\u00f9 importante lievito di deterioramento nel vino rosso. I fenoli 4-EP e 4-EG prodotti dal lievito causano difetti del vino che difficilmente possono essere rimossi. Se la nota &#8220;Brett&#8221; \u00e8 troppo intensa, gli enologi devono decidere se miscelare o addirittura scartare il vino con conseguenti danni economici. Tuttavia <em>Brettanomyces, <\/em>se presente a basse concentrazioni, pu\u00f2 essere utile perch\u00e9 aggiunge complessit\u00e0 ai semplici vini rossi. In ogni caso, \u00e8 necessaria molta cautela dal momento che il lievito pu\u00f2 diffondersi rapidamente all&#8217;interno degli impianti di produzione e contaminare altri prodotti.<\/p>\n<p>Il rilevamento di una possibile contaminazione da <em>Brettanomyces<\/em> \u00e8 quindi di fondamentale importanza per la garanzia della qualit\u00e0 durante la produzione del vino. Spesso vengono utilizzati i metodi di rilevazione microbiologica tradizionali, che sono economici ma forniscono risultati solo dopo circa 2 settimane. Nel nostro video, Ronald Niemeijer presenta un metodo di rilevamento molto pi\u00f9 veloce e preciso: <a href=\"https:\/\/www.youtube.com\/watch?v=czy1Hdmvvv4\">https:\/\/www.youtube.com\/watch?v=czy1Hdmvvv4<\/a><\/p>\n<h3>Rilevazione di <em>Brettanomyces<\/em> grazie ai kit GEN-IAL\u00ae QuickGEN<\/h3>\n<p>Il principale vantaggio dei test qPCR sono i tempi di attesa per i risultati, disponibili in poco tempo. Tuttavia, dal momento che la procedura analitica \u00e8 relativamente complessa, i test qPCR sono stati per lungo tempo utilizzati solo nell&#8217;ambito della ricerca. I moderni kit GEN-IAL\u00ae QuickGEN sono molto pi\u00f9 intuitivi e possono essere eseguiti anche da piccoli laboratori enologici e da principianti della PCR. Grazie ad una preparazione del DNA senza pre-arricchimento, ai tubi pre-riempiti e ai comodi template per i termociclatori, le fasi di lavoro sono ridotte al minimo e la procedura analitica \u00e8 estremamente semplificata. Le analisi possono quindi essere eseguite in modo pi\u00f9 rapido e conveniente rispetto ai test PCR convenzionali. Inoltre,\u00a0 grazie al formato del kit che necessita di pochi reagenti e strumenti aggiuntivi, il rischio di contaminazione \u00e8 ridotto al minimo. Infine il risultato \u00e8 gi\u00e0 disponibile entro 2 ore &#8211; qualitativamente o anche quantitativamente (CFU \/ ml) se si utilizza un controllo o una curva standard.<h4>GEN-IAL\u00ae QuickGEN Dekkera bruxellensis<\/h4><\/p>\n<ul>\n<li>Risultati veloci in sole 2 ore<\/li>\n<li>Altamente specifico<\/li>\n<li>Procedura analitica semplificata<\/li>\n<li>Adatto anche per piccoli laboratori<\/li>\n<li>Analisi qualitativa e quantitativa<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/food.r-biopharm.com\/wp-content\/uploads\/2019\/09\/qickgen-first-yeast-pcr-kit_laboratory_rgb_lowres_2019-08.jpg\" class=\"attachment-full size-full\" alt=\"gen-ial quickgen first yeast pcr kit brettanomyces\" \/><p><a href=\"\/?p=97881\" title=\"Informazioni sul prodotto\" class=\"button button--large\">Informazioni sul prodotto<\/a><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>I lieviti Brettanomyces provocano il cosiddetto &#8220;Brett&#8221; off-flavour: un odore sgradevole di cavallo, cuoio, sudore o persino urina. La rilevazione precoce di una possibile contaminazione \u00e8 di grande importanza per i viticoltori.<\/p>\n","protected":false},"author":27,"featured_media":119815,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"444","_seopress_titles_title":"Brettanomyces nel vino: come rilevare il deterioramento del lievito","_seopress_titles_desc":"I lieviti Brettanomyces provocano il cosiddetto \"Brett\" off-flavour: un odore sgradevole di cavallo, cuoio, sudore o urina. Una rilevazione precoce \u00e8 fondamentale.","_seopress_robots_index":"","_seopress_analysis_target_kw":"brettanomyces","content-type":"","_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","inline_featured_image":false,"footnotes":""},"analyte":[1290,1227,1716],"technology":[1235],"industry":[1374,712],"newstype":[],"class_list":["post-119881","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","analyte-beverage-spoilers-it","analyte-microbiologia","analyte-organismi-di-deterioramento-del-vino","technology-real-time-pcr-it","industry-analisi-del-vino","industry-bevande"],"acf":[],"_links":{"self":[{"href":"https:\/\/food.r-biopharm.com\/it\/wp-json\/wp\/v2\/posts\/119881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/food.r-biopharm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/food.r-biopharm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/food.r-biopharm.com\/it\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/food.r-biopharm.com\/it\/wp-json\/wp\/v2\/comments?post=119881"}],"version-history":[{"count":4,"href":"https:\/\/food.r-biopharm.com\/it\/wp-json\/wp\/v2\/posts\/119881\/revisions"}],"predecessor-version":[{"id":119886,"href":"https:\/\/food.r-biopharm.com\/it\/wp-json\/wp\/v2\/posts\/119881\/revisions\/119886"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/food.r-biopharm.com\/it\/wp-json\/wp\/v2\/media\/119815"}],"wp:attachment":[{"href":"https:\/\/food.r-biopharm.com\/it\/wp-json\/wp\/v2\/media?parent=119881"}],"wp:term":[{"taxonomy":"analyte","embeddable":true,"href":"https:\/\/food.r-biopharm.com\/it\/wp-json\/wp\/v2\/analyte?post=119881"},{"taxonomy":"technology","embeddable":true,"href":"https:\/\/food.r-biopharm.com\/it\/wp-json\/wp\/v2\/technology?post=119881"},{"taxonomy":"industry","embeddable":true,"href":"https:\/\/food.r-biopharm.com\/it\/wp-json\/wp\/v2\/industry?post=119881"},{"taxonomy":"newstype","embeddable":true,"href":"https:\/\/food.r-biopharm.com\/it\/wp-json\/wp\/v2\/newstype?post=119881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}